{"id":3169,"date":"2024-04-24T09:23:20","date_gmt":"2024-04-24T09:23:20","guid":{"rendered":"https:\/\/tronix.themepul.com\/software-company-demo\/?page_id=3169"},"modified":"2024-05-21T07:35:16","modified_gmt":"2024-05-21T07:35:16","slug":"contact","status":"publish","type":"page","link":"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3169\" class=\"elementor elementor-3169\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cabf669 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cabf669\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45685cea\" data-id=\"45685cea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2961d2ac elementor-widget elementor-widget-icon_box\" data-id=\"2961d2ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"tronix-icon-box-wrapper\">\n            <div class=\"container\">\n                <div class=\"row\">\n                                            <div class=\"col-xl-4 col-lg-4 col-md-6 \">\n                            <div class=\"tronix-icon-box\">\n                                                                    <div class=\"tronix-icon\">\n                                        <i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>                                    <\/div>\n                                                                <div class=\"icon-box-content\">\n                                    <div class=\"icon-box-title-label\"> Phone Number <\/div>\n                                                                            <h6 class=\"icon-box-title\">\n                                                                                            +569 (58) 3259-3256\n+569 (58) 3259-3256                                                                                        <\/h6>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-4 col-lg-4 col-md-6 \">\n                            <div class=\"tronix-icon-box\">\n                                                                    <div class=\"tronix-icon\">\n                                        <i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>                                    <\/div>\n                                                                <div class=\"icon-box-content\">\n                                    <div class=\"icon-box-title-label\"> Email Address <\/div>\n                                                                            <h6 class=\"icon-box-title\">\n                                                                                            info@tronix.com\ninside.24tronix.com                                                                                        <\/h6>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-4 col-lg-4 col-md-6 \">\n                            <div class=\"tronix-icon-box\">\n                                                                    <div class=\"tronix-icon\">\n                                        <i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>                                    <\/div>\n                                                                <div class=\"icon-box-content\">\n                                    <div class=\"icon-box-title-label\"> Office Address <\/div>\n                                                                            <h6 class=\"icon-box-title\">\n                                                                                            25 Hilton Street, Miana\nFrankfurt. DE                                                                                        <\/h6>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49a18d15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49a18d15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79647cca\" data-id=\"79647cca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-60eb046c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60eb046c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3c9aba1\" data-id=\"3c9aba1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-641d70aa elementor-widget elementor-widget-tronix_about\" data-id=\"641d70aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tronix_about.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"about-section-wraper\">\n            <div class=\"container\">\n                <div class=\"about_content \">\n                    <div class=\"about-item\">\n                                                                            <h2 class=\"about-title\"> \n                            We'd love to hear\nfrom you.                             <\/h2>\n                                                 <div class=\"about-des\">\n                                At our IT solution company, we are committed to providing exceptional customer service and support. If you are experiencing technical difficulties or need assistance with one of our services,                            <\/div>\n                                                                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fedc806 elementor-widget elementor-widget-Tronix List\" data-id=\"4fedc806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Tronix List.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"tronix_list-wrapper\">\n            <div class=\"container\">\n                <div class=\"row \">\n                                            <div class=\"tronix-section-list-title\"> Your benefits: <\/div>\n                                                                <div class=\"col-xl-6 col-lg-6 col-md-6 col-12\">\n                            <div class=\"tronix-list-box-item \">\n                                <div class=\"tronix-list-icon\">\n                                    <i aria-hidden=\"true\" class=\"bi bi-check2\"><\/i>                                <\/div>\n                                                                    <div class=\"tronix-list-title\">  Client-oriented\n <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-6 col-lg-6 col-md-6 col-12\">\n                            <div class=\"tronix-list-box-item \">\n                                <div class=\"tronix-list-icon\">\n                                    <i aria-hidden=\"true\" class=\"bi bi-check2\"><\/i>                                <\/div>\n                                                                    <div class=\"tronix-list-title\">  Independent\n <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-6 col-lg-6 col-md-6 col-12\">\n                            <div class=\"tronix-list-box-item \">\n                                <div class=\"tronix-list-icon\">\n                                    <i aria-hidden=\"true\" class=\"bi bi-check2\"><\/i>                                <\/div>\n                                                                    <div class=\"tronix-list-title\">  Competent <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-6 col-lg-6 col-md-6 col-12\">\n                            <div class=\"tronix-list-box-item \">\n                                <div class=\"tronix-list-icon\">\n                                    <i aria-hidden=\"true\" class=\"bi bi-check2\"><\/i>                                <\/div>\n                                                                    <div class=\"tronix-list-title\">  Results-driven <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-6 col-lg-6 col-md-6 col-12\">\n                            <div class=\"tronix-list-box-item \">\n                                <div class=\"tronix-list-icon\">\n                                    <i aria-hidden=\"true\" class=\"bi bi-check2\"><\/i>                                <\/div>\n                                                                    <div class=\"tronix-list-title\">  Problem-solving <\/div>\n                                                            <\/div>\n                        <\/div>\n                                            <div class=\"col-xl-6 col-lg-6 col-md-6 col-12\">\n                            <div class=\"tronix-list-box-item \">\n                                <div class=\"tronix-list-icon\">\n                                    <i aria-hidden=\"true\" class=\"bi bi-check2\"><\/i>                                <\/div>\n                                                                    <div class=\"tronix-list-title\">  Transparent <\/div>\n                                                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-57c8b17b\" data-id=\"57c8b17b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-131152fd elementor-widget elementor-widget-tronix_ctf7\" data-id=\"131152fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tronix_ctf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"tronix-ctf7s-wrapper\">\n            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f991-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"991\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/help-desk-demo\/wp-json\/wp\/v2\/pages\/3169#wpcf7-f991-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"991\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f991-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"tronix-contact-from-one-wrappwr\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-lg-6 col-md-6 col-12\">\n                <div class=\"tronix-input-area\">\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"fname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"You Name\" value=\"\" type=\"text\" name=\"fname\" \/><\/span>\n                <\/div>\n            <\/div>\n            <div class=\"col-lg-6 col-md-6 col-12\">\n                <div class=\"tronix-input-area\">\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email Address\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n                <\/div>\n            <\/div>\n            <div class=\"col-lg-12 col-md-12 col-12\">\n                <div class=\"tronix-input-area\">\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"select\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"select\"><option value=\"Basic\">Basic<\/option><option value=\"Advance\">Advance<\/option><\/select><\/span>\n                <\/div>\n            <\/div>\n\n            <div class=\"col-lg-12 col-md-12 col-12\">\n                <div class=\"tronix-input-area message\">\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"10\" rows=\"6\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"message\"><\/textarea><\/span>\n                <\/div>\n                <div class=\"tronix-contact-button button\">\n                    <input class=\"wpcf7-form-control wpcf7-submit has-spinner theme-btns\" type=\"submit\" value=\"Submit Message\" \/>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Phone Number +569 (58) 3259-3256 +569 (58) 3259-3256 Email Address info@tronix.com inside.24tronix.com Office Address 25 Hilton Street, Miana Frankfurt. DE We&#8217;d love to hear from you. At our IT solution company, we are committed to providing exceptional customer service and support. If you are experiencing technical difficulties or need assistance with one of our services, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"blank-template.php","meta":{"footnotes":""},"class_list":["post-3169","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact Us - Help Desk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us - Help Desk\" \/>\n<meta property=\"og:description\" content=\"Phone Number +569 (58) 3259-3256 +569 (58) 3259-3256 Email Address info@tronix.com inside.24tronix.com Office Address 25 Hilton Street, Miana Frankfurt. DE We&#8217;d love to hear from you. At our IT solution company, we are committed to providing exceptional customer service and support. If you are experiencing technical difficulties or need assistance with one of our services, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Help Desk\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T07:35:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/contact\\\/\",\"url\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/contact\\\/\",\"name\":\"Contact Us - Help Desk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/#website\"},\"datePublished\":\"2024-04-24T09:23:20+00:00\",\"dateModified\":\"2024-05-21T07:35:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/#website\",\"url\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/\",\"name\":\"Help Desk\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tronix.themepul.com\\\/help-desk-demo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us - Help Desk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/","og_locale":"en_US","og_type":"article","og_title":"Contact Us - Help Desk","og_description":"Phone Number +569 (58) 3259-3256 +569 (58) 3259-3256 Email Address info@tronix.com inside.24tronix.com Office Address 25 Hilton Street, Miana Frankfurt. DE We&#8217;d love to hear from you. At our IT solution company, we are committed to providing exceptional customer service and support. If you are experiencing technical difficulties or need assistance with one of our services, [&hellip;]","og_url":"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/","og_site_name":"Help Desk","article_modified_time":"2024-05-21T07:35:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/","url":"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/","name":"Contact Us - Help Desk","isPartOf":{"@id":"https:\/\/tronix.themepul.com\/help-desk-demo\/#website"},"datePublished":"2024-04-24T09:23:20+00:00","dateModified":"2024-05-21T07:35:16+00:00","breadcrumb":{"@id":"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tronix.themepul.com\/help-desk-demo\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tronix.themepul.com\/help-desk-demo\/"},{"@type":"ListItem","position":2,"name":"Contact Us"}]},{"@type":"WebSite","@id":"https:\/\/tronix.themepul.com\/help-desk-demo\/#website","url":"https:\/\/tronix.themepul.com\/help-desk-demo\/","name":"Help Desk","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tronix.themepul.com\/help-desk-demo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/tronix.themepul.com\/help-desk-demo\/wp-json\/wp\/v2\/pages\/3169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tronix.themepul.com\/help-desk-demo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tronix.themepul.com\/help-desk-demo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tronix.themepul.com\/help-desk-demo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tronix.themepul.com\/help-desk-demo\/wp-json\/wp\/v2\/comments?post=3169"}],"version-history":[{"count":0,"href":"https:\/\/tronix.themepul.com\/help-desk-demo\/wp-json\/wp\/v2\/pages\/3169\/revisions"}],"wp:attachment":[{"href":"https:\/\/tronix.themepul.com\/help-desk-demo\/wp-json\/wp\/v2\/media?parent=3169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}